{"id":12214,"date":"2015-09-15T00:00:00","date_gmt":"2015-09-14T22:00:00","guid":{"rendered":"https:\/\/libinst.detail-digital.ch\/denkanstoesse\/rapporto-annuale-sulla-liberta-economica-2015\/"},"modified":"2015-09-15T00:00:00","modified_gmt":"2015-09-14T22:00:00","slug":"rapporto-annuale-sulla-liberta-economica-2015","status":"publish","type":"denkanstoesse","link":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/","title":{"rendered":"Rapporto annuale sulla libert\u00e0 economica 2015"},"content":{"rendered":"<p>Il rapporto sulla libert\u00e0 economica nel mondo per l&#8217;anno 2015, pubblicato in Svizzera dall&#8217;Istituto Liberale, mostra che l&#8217;autodeterminazione economica aumenta la felicit\u00e0 personale. Rispetto al rapporto precedente, la libert\u00e0 economica mondiale \u00e8 in leggero aumento con un&#8217;evoluzione dell&#8217;omonimo indice da 6.84 a 6.86 (su una scala da 1 a 10). La Svizzera rimane il paese del continente europeo con la libert\u00e0 economica pi\u00f9 elevata e conserva la sua ottima quarta posizione mondiale.<\/p>\n<p>Hong Kong si rivela nuovamente il paese con la libert\u00e0 economica pi\u00f9 elevata, seguito a ruota da Singapore e dalla Nuova Zelanda. Questo risultato suggerisce che la formula \u00abone country, two systems\u00bb \u00e8 ancora in vigore. Tuttavia, la posizione di Hong Kong \u00e8 minacciata dall&#8217;eventualit\u00e0 che la Cina, che si classifica unicamente 111esima su 157 paesi analizzati, possa limitare sempre di pi\u00f9 il margine di manovra della sua regione amministrativa speciale. Tra le regressioni pi\u00f9 spettacolari rispetto al rapporto dell&#8217;anno scorso sono da segnalare gli Stati Uniti che passano dalla 12esima alla 16esima posizione e la Francia che scivola dalla 58esima alla 70esima posizione. Inevitabilmente, le politiche pubbliche dei governi di questi paesi cominciano ad avere le prevedibili conseguenze negative per la libert\u00e0 economica dei loro cittadini. La classifica di quest&#8217;anno \u00e8 chiusa dalla Libia, la Repubblica del Congo e il Venezuela. Le dittature come Cuba e la Corea del Nord non sono analizzate per mancanza di dati.<\/p>\n<h3>Libert\u00e0 economica e felicit\u00e0<\/h3>\n<p>La ricerca realizzata quest&#8217;anno stabilisce una correlazione positiva tra le libert\u00e0 economiche e la felicit\u00e0 individuale. Gli economisti Hans Pitlik, dell&#8217;Istituto viennese di ricerca economica (Wifo) in Austria, Dulce M. Redin e Martin Rode, dell&#8217;universit\u00e0 di Navarra in Spagna, hanno scoperto che un pi\u00f9 grande controllo sulla propria vita da un punto di vista economico aumenta la felicit\u00e0 e questo indipendentemente dall&#8217;evoluzione del prodotto interno lordo per abitante o di altre misure della prosperit\u00e0. Utilizzando i dati dell&#8217;indagine mondiale sui valori (World Values Survey) e dello studio europeo sui valori (European Values Study) gli autori sono riusciti a dimostrare che la libert\u00e0 economica influisce fortemente e in maniera duratura sulla soddisfazione personale. Questa osservazione conferma i risultati gi\u00e0 ottenuti dalle precedenti ricerche sulla felicit\u00e0.<\/p>\n<p>Il legame positivo tra le libert\u00e0 economiche e i differenti indicatori di qualit\u00e0 della vita come il reddito, la crescita economica, la riduzione della povert\u00e0 e la speranza di vita \u00e8 anch&#8217;esso confermata. Gli stati nel quartile dei paesi pi\u00f9 liberi hanno un reddito medio per abitante (corretto in funzione del potere d&#8217;acquisto) di 38.601 dollari mentre gli stati dell&#8217;ultimo quartile totalizzano unicamente 6986 dollari. Il reddito medio del 10% degli abitanti pi\u00f9 poveri del primo quartile \u00e8 di 9881 mentre il 10% dei pi\u00f9 poveri dell&#8217;ultimo quartile devono accontentarsi di 1629 dollari. La speranza di vita nelle economie pi\u00f9 liberali \u00e8 di 80,1 anni mentre si ferma a 63.1 per le economie pi\u00f9 represse.<\/p>\n<h3>La Svizzera nel confronto internazionale<\/h3>\n<p>L&#8217;indice di libert\u00e0 economica, concettualizzato tra gli altri dai Nobel Milton Friedman, Douglass C. North e Gary Becker, \u00e8 una referenza scientifica in materia. Esso valuta il contesto istituzionale di un paese sulla base di 42 indicatori raggruppati in 5 ambiti. Quest&#8217;anno, la Svizzera ha ottenuto i seguenti valori (sempre su una scala da 1 a 10, 10 rappresentante il livello ottimale di libert\u00e0 economica.<\/p>\n<ul>\n<li>Ampiezza dell&#8217;attivit\u00e0 statale: stabile a 7,7 rispetto all&#8217;anno scorso;<\/li>\n<li>Sicurezza del diritto e protezione della propriet\u00e0 privata: leggera deteriorazione da 8,4 a 8,3;<\/li>\n<li>Accesso a una moneta stabile: miglioramento da 9,4 a 9,7;<\/li>\n<li>Libert\u00e0 del commercio mondiale: leggera diminuzione da 7,2 a 7,1;<\/li>\n<li>Densit\u00e0 della regolazione: deterioramento da 8,3 a 8,1.<\/li>\n<\/ul>\n<p>La Svizzera \u00e8 soprattutto penalizzata dal suo protezionismo agricolo e dagli attacchi legali e giurisprudenziali alla sicurezza del diritto, sicurezza che \u00e8 diminuita di quasi un punto dall&#8217;inizio del decennio. La densificazione della regolazione, la pianificazione pi\u00f9 restrittiva e centralizzata del territorio e la giurisprudenza tendenzialmente poco accomodante dei tribunali spiegano questa diminuzione.<\/p>\n<p>Tra i 10 paesi pi\u00f9 liberi, accanto a Hong Kong (8,97 punti su 10), Singapore (8,52), la Nuova Zelanda (8,19) e la Svizzera (8,16), si trovano gli Emirati arabi uniti (8,15), l&#8217;isola di Mauritius (8,08), la Giordania (7,93), l&#8217;Irlanda (7,90), primo paese dell&#8217;Unione europea, il Canada (7,89) e la Gran Bretagna (7,87).<\/p>\n<p>Tra le pi\u00f9 grandi economie, il Giappone si classifica 26esimo (7,52), la Germania 29esima (7,50), la Francia 70esima (7,12) e l&#8217;Italia 68esima (7,13). L&#8217;India si classifica unicamente 114esima (6,43), la Cina 111esima (6,44), il Brasile 118esimo (6,34) e la Russia 99esima (6,69). Questi punteggi mostrano che questi paesi dispongono ancora di un forte potenziale di liberalizzazione.<\/p>\n<p class=\"left\"><strong>Leggere il rapporto:<br \/>\n<a href=\"http:\/\/www.libinst.ch\/publications\/IL-EFW-2015.pdf\" rel=\"external\">Economic Freedom of the World<\/a><\/strong> (258 pagine, PDF)<\/p>\n","protected":false},"featured_media":11293,"template":"","tag":[1590,158,157,510],"class_list":["post-12214","denkanstoesse","type-denkanstoesse","status-publish","has-post-thumbnail","hentry","tags-indice-della-liberta-economica-it","tags-liberta-economica-e-crescita","tags-regolamentazione","tags-svizzera"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rapporto annuale sulla libert\u00e0 economica 2015 - Istituto Liberale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rapporto annuale sulla libert\u00e0 economica 2015 - Istituto Liberale\" \/>\n<meta property=\"og:description\" content=\"Il rapporto sulla libert\u00e0 economica nel mondo per l&#8217;anno 2015, pubblicato in Svizzera dall&#8217;Istituto Liberale, mostra che l&#8217;autodeterminazione economica aumenta la felicit\u00e0 personale. Rispetto al rapporto precedente, la libert\u00e0 economica mondiale \u00e8 in leggero aumento con un&#8217;evoluzione dell&#8217;omonimo indice da 6.84 a 6.86 (su una scala da 1 a 10). La Svizzera rimane il paese [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Liberale\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/zurich-city.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1223\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/rapporto-annuale-sulla-liberta-economica-2015\\\/\",\"url\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/rapporto-annuale-sulla-liberta-economica-2015\\\/\",\"name\":\"Rapporto annuale sulla libert\u00e0 economica 2015 - Istituto Liberale\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/rapporto-annuale-sulla-liberta-economica-2015\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/rapporto-annuale-sulla-liberta-economica-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/zurich-city.jpg\",\"datePublished\":\"2015-09-14T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/rapporto-annuale-sulla-liberta-economica-2015\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/rapporto-annuale-sulla-liberta-economica-2015\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/rapporto-annuale-sulla-liberta-economica-2015\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/zurich-city.jpg\",\"contentUrl\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/zurich-city.jpg\",\"width\":1920,\"height\":1223,\"caption\":\"Scenic panoramic view of historic Z\u00fcrich city center with famous Fraum\u00fcnster and Grossm\u00fcnster Church and river Limmat at Lake Zurich on a beautiful sunny day with blue sky in summer, Switzerland\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/rapporto-annuale-sulla-liberta-economica-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.libinst.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rapporto annuale sulla libert\u00e0 economica 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"Istituto Liberale\",\"description\":\"\",\"publisher\":{\"@id\":\"\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"\\\/#organization\",\"name\":\"Istituto Liberale\",\"url\":\"\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-instituto-liberale.png\",\"contentUrl\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-instituto-liberale.png\",\"width\":2935,\"height\":458,\"caption\":\"Istituto Liberale\"},\"image\":{\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rapporto annuale sulla libert\u00e0 economica 2015 - Istituto Liberale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/","og_locale":"it_IT","og_type":"article","og_title":"Rapporto annuale sulla libert\u00e0 economica 2015 - Istituto Liberale","og_description":"Il rapporto sulla libert\u00e0 economica nel mondo per l&#8217;anno 2015, pubblicato in Svizzera dall&#8217;Istituto Liberale, mostra che l&#8217;autodeterminazione economica aumenta la felicit\u00e0 personale. Rispetto al rapporto precedente, la libert\u00e0 economica mondiale \u00e8 in leggero aumento con un&#8217;evoluzione dell&#8217;omonimo indice da 6.84 a 6.86 (su una scala da 1 a 10). La Svizzera rimane il paese [&hellip;]","og_url":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/","og_site_name":"Istituto Liberale","og_image":[{"width":1920,"height":1223,"url":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/zurich-city.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/","url":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/","name":"Rapporto annuale sulla libert\u00e0 economica 2015 - Istituto Liberale","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/#primaryimage"},"image":{"@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/zurich-city.jpg","datePublished":"2015-09-14T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/#primaryimage","url":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/zurich-city.jpg","contentUrl":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/zurich-city.jpg","width":1920,"height":1223,"caption":"Scenic panoramic view of historic Z\u00fcrich city center with famous Fraum\u00fcnster and Grossm\u00fcnster Church and river Limmat at Lake Zurich on a beautiful sunny day with blue sky in summer, Switzerland"},{"@type":"BreadcrumbList","@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/rapporto-annuale-sulla-liberta-economica-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.libinst.ch\/"},{"@type":"ListItem","position":2,"name":"Rapporto annuale sulla libert\u00e0 economica 2015"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Istituto Liberale","description":"","publisher":{"@id":"\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"\/#organization","name":"Istituto Liberale","url":"\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/#\/schema\/logo\/image\/","url":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/08\/logo-instituto-liberale.png","contentUrl":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/08\/logo-instituto-liberale.png","width":2935,"height":458,"caption":"Istituto Liberale"},"image":{"@id":"\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/denkanstoesse\/12214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/denkanstoesse"}],"about":[{"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/types\/denkanstoesse"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/media\/11293"}],"wp:attachment":[{"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/media?parent=12214"}],"wp:term":[{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/tag?post=12214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}