{"id":12244,"date":"2016-09-09T00:00:00","date_gmt":"2016-09-08T22:00:00","guid":{"rendered":"https:\/\/libinst.detail-digital.ch\/denkanstoesse\/indice-della-liberta-economica-2016\/"},"modified":"2016-09-09T00:00:00","modified_gmt":"2016-09-08T22:00:00","slug":"indice-della-liberta-economica-2016","status":"publish","type":"denkanstoesse","link":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/","title":{"rendered":"Rapporto annuale sulla libert\u00e0 economica 2016"},"content":{"rendered":"<p>La Svizzera rimane nel 2016 la nazione con la libert\u00e0 economica pi\u00f9 estesa di tutto il continente europeo. Questo \u00e8 quanto indica il rapporto annuale 2016 dell&#8217;indice della libert\u00e0 economica nel mondo, rapporto pubblicato ogni anno in Svizzera dall&#8217;Istituto Liberale.<\/p>\n<p>Hong Kong conferma ancora una volta la sua posizione di leader della libert\u00e0 economica, seguito da Singapore, dalla Nuova Zelanda e dalla Svizzera. Gli Stati Uniti, che nel 2000 potevano ancora fregiarsi della seconda posizione, si piazzano oramai solo alla 16esima. Tra i principali perdenti della classifica di quest&#8217;anno si trova il Giappone (40esimo, l&#8217;anno scorso 26esimo), mentre la Francia ha sorprendentemente recuperato un po&#8217; di terreno salendo dalla 70esima alle 57esima posizione. La Repubblica del Congo, la Libia e il Venezuela chiudono la classifica. Si noti che le dittature, come Cuba e la Corea del Nord, non sono valutate a causa dell&#8217;assenza di dati affidabili.<\/p>\n<p>Il rapporto conferma l&#8217;esistenza di una stretta relazione tra libert\u00e0 economica e prosperit\u00e0. Il quartile delle nazioni pi\u00f9 libere ha un prodotto interno lordo per abitante medio di 41&#8217;228 dollari, mentre il quartile delle nazioni pi\u00f9 repressive raggiungono unicamente una media di 5&#8217;471 dollari. Il 10% pi\u00f9 povero dalla popolazione delle nazioni pi\u00f9 libere ha un reddito medio per abitante di 11&#8217;283 dollari, montante ben pi\u00f9 elevato del reddito medio raggiunto nelle nazioni pi\u00f9 repressive. Inoltre, la speranza di vita \u00e8 di 80,4 anni nelle nazioni del quartile pi\u00f9 libero e solo di 64 anni nel quartile delle nazioni pi\u00f9 repressive.<\/p>\n<h3>L&#8217;ideologia socialista, nemico numero uno della prosperit\u00e0<\/h3>\n<p>Il rapporto di quest&#8217;anno dedica un capitolo speciale alla regressione del Venezuela. Questo paese, che si trovava ancora nel 1980 alla 14esima posizione dei paesi economicamente pi\u00f9 liberi, chiude ormai la classifica mondiale da 4 anni. Il suo declino \u00e8 cominciato prima dell&#8217;arrivo al potere, nel 1999, d&#8217;Hugo Chavez e del suo Partito socialista. Tuttavia, sotto la presidenza del suo successore, un ritorno ad un&#8217;economia di libero mercato \u00e8 da escludere a breve termine. Le conseguenze della fantomatica &#8220;rivoluzione bolivariana&#8221; di Chavez penalizzano la prosperit\u00e0 del paese pi\u00f9 di tutte le barriere sociali e culturali esistenti nei paesi in via di sviluppo. Questo dimostra come la libert\u00e0 economica non sia qualcosa di garantito, ma bens\u00ec il risultato di una relazione virtuosa tra cultura e istituzioni politiche.<\/p>\n<p>Un altro capitolo \u00e8 dedicato ai pessimi risultati relativi degli Stati Uniti (16esimi ormai da due anni consecutivi). Questi risultati sono attribuiti alla crescita del settore statale, all&#8217;indebolimento del quadro giuridico e alle risposte keynesiane e interventiste alla crisi dei subprime e del settore bancario a partire dal 2007.<\/p>\n<h3>La Svizzera nel raffronto internazionale<\/h3>\n<p>Nel 2016, la Svizzera ha beneficiato di un leggero aumento del suo indice e ha raggiunto i punteggi seguenti su una scala da 1 (libert\u00e0 minima) a 10 (libert\u00e0 ottimale):<\/p>\n<ul>\n<li>Estensione dell&#8217;attivit\u00e0 statale: stabile rispetto all&#8217;anno scorso, 7,7<\/li>\n<li>Stato di diritto e protezione della propriet\u00e0 privata: aumento da 8,3 a 8,5<\/li>\n<li>Accesso ad una moneta stabile: leggero miglioramento da 9,7 a 9,8<\/li>\n<li>Libert\u00e0 del commercio mondiale: miglioramento da 7,1 a 7,3<\/li>\n<li>Densit\u00e0 regolamentare: leggero peggioramento da 8,1 a 8,0<\/li>\n<\/ul>\n<p>La Svizzera ha potuto soprattutto conservare la sua ottima posizione grazie all&#8217;estensione della sua rete di libero scambio e ai meccanismi di freno all&#8217;indebitamento che limitano l&#8217;espansione di un settore pubblico che rimane tuttavia sovradimensionato.<\/p>\n<p>Tra i 10 paesi economicamente pi\u00f9 liberi si trovano, oltre a Hong Kong (9,0), Singapore (8,7), Nuova Zelanda (8,4) e Svizzera (8,3), anche il Canada (8,0), la Georgia (8,0), l&#8217;Irlanda (8,0), le isole Mauritius (8,0), gli Emirati Arabi Uniti (8,0), l&#8217;Australia (7,9) e il Regno Unito (7,9). Tra le altre grandi economie industriali, la Germania si posiziona 30esima, la Corea del Sud 42esima e l&#8217;Italia 69esima. Il Messico si piazza all&#8217;88esima posizione, ben davanti alla Russia (102esima), all&#8217;India (112esima), alla Cina (113esima) e al Brasile (124esimo).<\/p>\n<p class=\"center\"><strong>Leggere il rapporto (in inglese):<br \/>\n<a href=\"http:\/\/www.libinst.ch\/publications\/IL-EFW-2016.pdf\" rel=\"external\">Economic Freedom of the World<\/a><\/strong> (328 pagine, PDF)<\/p>\n","protected":false},"featured_media":9809,"template":"","tag":[1590,158,157,510],"class_list":["post-12244","denkanstoesse","type-denkanstoesse","status-publish","has-post-thumbnail","hentry","tags-indice-della-liberta-economica-it","tags-liberta-economica-e-crescita","tags-regolamentazione","tags-svizzera"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rapporto annuale sulla libert\u00e0 economica 2016 - Istituto Liberale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rapporto annuale sulla libert\u00e0 economica 2016 - Istituto Liberale\" \/>\n<meta property=\"og:description\" content=\"La Svizzera rimane nel 2016 la nazione con la libert\u00e0 economica pi\u00f9 estesa di tutto il continente europeo. Questo \u00e8 quanto indica il rapporto annuale 2016 dell&#8217;indice della libert\u00e0 economica nel mondo, rapporto pubblicato ogni anno in Svizzera dall&#8217;Istituto Liberale. Hong Kong conferma ancora una volta la sua posizione di leader della libert\u00e0 economica, seguito [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Liberale\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/lausanne-city.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/indice-della-liberta-economica-2016\\\/\",\"url\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/indice-della-liberta-economica-2016\\\/\",\"name\":\"Rapporto annuale sulla libert\u00e0 economica 2016 - Istituto Liberale\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/indice-della-liberta-economica-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/indice-della-liberta-economica-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/lausanne-city.jpg\",\"datePublished\":\"2016-09-08T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/indice-della-liberta-economica-2016\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/indice-della-liberta-economica-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/indice-della-liberta-economica-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/lausanne-city.jpg\",\"contentUrl\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/lausanne-city.jpg\",\"width\":1920,\"height\":1282,\"caption\":\"Lausanne city, view of the historical gothic Cathedral, Old town roofs and Lake Geneva, Switzerland\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.libinst.ch\\\/it\\\/spunti-di-riflessione\\\/indice-della-liberta-economica-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.libinst.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rapporto annuale sulla libert\u00e0 economica 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"Istituto Liberale\",\"description\":\"\",\"publisher\":{\"@id\":\"\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"\\\/#organization\",\"name\":\"Istituto Liberale\",\"url\":\"\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-instituto-liberale.png\",\"contentUrl\":\"https:\\\/\\\/www.libinst.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-instituto-liberale.png\",\"width\":2935,\"height\":458,\"caption\":\"Istituto Liberale\"},\"image\":{\"@id\":\"\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rapporto annuale sulla libert\u00e0 economica 2016 - Istituto Liberale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/","og_locale":"it_IT","og_type":"article","og_title":"Rapporto annuale sulla libert\u00e0 economica 2016 - Istituto Liberale","og_description":"La Svizzera rimane nel 2016 la nazione con la libert\u00e0 economica pi\u00f9 estesa di tutto il continente europeo. Questo \u00e8 quanto indica il rapporto annuale 2016 dell&#8217;indice della libert\u00e0 economica nel mondo, rapporto pubblicato ogni anno in Svizzera dall&#8217;Istituto Liberale. Hong Kong conferma ancora una volta la sua posizione di leader della libert\u00e0 economica, seguito [&hellip;]","og_url":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/","og_site_name":"Istituto Liberale","og_image":[{"width":1920,"height":1282,"url":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/lausanne-city.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/","url":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/","name":"Rapporto annuale sulla libert\u00e0 economica 2016 - Istituto Liberale","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/#primaryimage"},"image":{"@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/lausanne-city.jpg","datePublished":"2016-09-08T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/#primaryimage","url":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/lausanne-city.jpg","contentUrl":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/05\/lausanne-city.jpg","width":1920,"height":1282,"caption":"Lausanne city, view of the historical gothic Cathedral, Old town roofs and Lake Geneva, Switzerland"},{"@type":"BreadcrumbList","@id":"https:\/\/www.libinst.ch\/it\/spunti-di-riflessione\/indice-della-liberta-economica-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.libinst.ch\/"},{"@type":"ListItem","position":2,"name":"Rapporto annuale sulla libert\u00e0 economica 2016"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Istituto Liberale","description":"","publisher":{"@id":"\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"\/#organization","name":"Istituto Liberale","url":"\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"\/#\/schema\/logo\/image\/","url":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/08\/logo-instituto-liberale.png","contentUrl":"https:\/\/www.libinst.ch\/wp-content\/uploads\/2023\/08\/logo-instituto-liberale.png","width":2935,"height":458,"caption":"Istituto Liberale"},"image":{"@id":"\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/denkanstoesse\/12244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/denkanstoesse"}],"about":[{"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/types\/denkanstoesse"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/media\/9809"}],"wp:attachment":[{"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/media?parent=12244"}],"wp:term":[{"taxonomy":"tags","embeddable":true,"href":"https:\/\/www.libinst.ch\/it\/wp-json\/wp\/v2\/tag?post=12244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}